{"id":2625,"date":"2023-11-03T17:05:36","date_gmt":"2023-11-03T16:05:36","guid":{"rendered":"https:\/\/newone.onesails.com\/?post_type=one-design&#038;p=2625"},"modified":"2024-03-10T21:45:21","modified_gmt":"2024-03-10T20:45:21","slug":"meteor","status":"publish","type":"one-design","link":"https:\/\/www.onesails.com\/fr\/one-design\/meteor\/","title":{"rendered":"METEOR"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":2628,"menu_order":0,"template":"","meta":{"_acf_changed":false},"one-design-taxonomy":[130],"class_list":["post-2625","one-design","type-one-design","status-publish","has-post-thumbnail","hentry","one-design-taxonomy-keelboat"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/one-design\/2625","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/one-design"}],"about":[{"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/types\/one-design"}],"version-history":[{"count":3,"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/one-design\/2625\/revisions"}],"predecessor-version":[{"id":17658,"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/one-design\/2625\/revisions\/17658"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/media\/2628"}],"wp:attachment":[{"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/media?parent=2625"}],"wp:term":[{"taxonomy":"one-design-taxonomy","embeddable":true,"href":"https:\/\/www.onesails.com\/fr\/wp-json\/wp\/v2\/one-design-taxonomy?post=2625"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}