{"id":2884,"date":"2023-11-04T11:53:40","date_gmt":"2023-11-04T10:53:40","guid":{"rendered":"https:\/\/newone.onesails.com\/?post_type=one-design&#038;p=2884"},"modified":"2024-04-03T18:56:05","modified_gmt":"2024-04-03T16:56:05","slug":"m32-speed","status":"publish","type":"one-design","link":"https:\/\/www.onesails.com\/da\/one-design\/m32-speed\/","title":{"rendered":"M32 Speed"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"one-design-taxonomy":[129],"class_list":["post-2884","one-design","type-one-design","status-publish","hentry","one-design-taxonomy-multihull"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/one-design\/2884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/one-design"}],"about":[{"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/types\/one-design"}],"version-history":[{"count":6,"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/one-design\/2884\/revisions"}],"predecessor-version":[{"id":23311,"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/one-design\/2884\/revisions\/23311"}],"wp:attachment":[{"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/media?parent=2884"}],"wp:term":[{"taxonomy":"one-design-taxonomy","embeddable":true,"href":"https:\/\/www.onesails.com\/da\/wp-json\/wp\/v2\/one-design-taxonomy?post=2884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}